{"id":172,"date":"2013-02-15T17:04:22","date_gmt":"2013-02-15T16:04:22","guid":{"rendered":"http:\/\/paganellamolveno.it\/?page_id=172"},"modified":"2023-09-18T11:49:32","modified_gmt":"2023-09-18T09:49:32","slug":"hotel","status":"publish","type":"page","link":"https:\/\/paganellamolveno.it\/it\/hotel\/","title":{"rendered":"Hotel"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row el_id=&#8221;servizi&#8221;][vc_column][vc_empty_space][vc_column_text]<\/p>\n<h2>Servizi generali<\/h2>\n<p>[\/vc_column_text][vc_row_inner][vc_column_inner width=&#8221;5\/12&#8243; css=&#8221;.vc_custom_1548757933648{margin-bottom: 0px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1695030465831{margin-bottom: 0px !important;}&#8221;]<\/p>\n<ul>\n<li>&#8211; ascensore<\/li>\n<li><em>&#8211; terrazza\/solarium<\/em><\/li>\n<li>&#8211; bar\/reception<\/li>\n<li>&#8211; piccolo giardino<\/li>\n<li>&#8211; sala TV, sala lettura<\/li>\n<li>&#8211; TV Sat<\/li>\n<li>&#8211; Trentino Card<\/li>\n<li><em>&#8211; parcheggio privato gratuito fino ad esaurimento<\/em><\/li>\n<li><\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;7\/12&#8243;][vc_column_text]<\/p>\n<ul>\n<li>&#8211; WiFi gratuito<\/li>\n<li>&#8211; pet friendly (S\/M size)<\/li>\n<li>&#8211; piccolo box bici (max 6)<\/li>\n<li>&#8211; 5\/10% di sconto in alcuni ristoranti della zona<\/li>\n<li>&#8211; pranzo a sacco, su richiesta<\/li>\n<li>&#8211; possibilit\u00e0 di prenotare per la sera, dei taglieri.<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_column_text]<strong>Trentino card <\/strong><\/p>\n<p>Con la TRENTINO GUEST CARD anche la tua auto va in vacanza! Avrete, infatti, diritto ai trasporti regionali gratuiti.<\/p>\n<p><strong>Parcheggio<\/strong><\/p>\n<p>Il parcheggio di fronte all&#8217;hotel \u00e8 <strong>gratuito<\/strong> ed \u00e8 <strong>disponibile fino ad esaurimento<\/strong>! <strong>se si parcheggia in seconda fila, prego lasciare le chiavi in reception<\/strong>. <em data-wp-editing=\"1\">Da liberare la mattina del giorno della partenza.<\/em><\/p>\n<ul>\n<li>&#8211; A 100 m, parcheggio comunale gratuito &#8220;Valbinaghe&#8221;<\/li>\n<li><strong>&#8211; FREE BUS<\/strong> per raggiungere ogni parte del paese (da met\u00e0 giugno a met\u00e0 settembre ca)<\/li>\n<\/ul>\n<p><strong>Pet friendly<\/strong><\/p>\n<p>L\u2019albergo accetta animali solo di piccola e media taglia ben educati e su richiesta. <em><strong>Hanno accesso a tutte le zone comuni fuorch\u00e9 in sala da pranzo! <\/strong><\/em>Eventualmente \u00e8 possibile fare colazione in terrazza o al bar al piano terra con il proprio amico a quattro zampe<em>. Previsto supplemento.\u00a0<\/em>[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_id=&#8221;colazione&#8221;][vc_column][vc_empty_space][vc_column_text]<\/p>\n<h2>Colazione<\/h2>\n<p>[\/vc_column_text][vc_column_text]A buffet dolce e salato, con ricco buffet di marmellate, cereali, biscotti, yogurt, brioches, dolci fatti in casa, uova, formaggi\/affetatti&#8230;etc. Dalle 8.00 alle 10.15.<\/p>\n<ul>\n<li>&#8211; A richiesta <strong><em>early-bird breakfast<\/em><\/strong>: dalle 7.30.<\/li>\n<li>&#8211; A richiesta packet-breakfast.<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div id='gallery-1' class='gallery galleryid-172 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/paganellamolveno.it\/it\/colazione-02-hotel-paganella-molveno\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/paganellamolveno.it\/wp-content\/uploads\/2019\/01\/colazione-02-hotel-paganella-molveno-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/paganellamolveno.it\/it\/colazione-04-hotel-paganella-molveno\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/paganellamolveno.it\/wp-content\/uploads\/2019\/01\/colazione-04-hotel-paganella-molveno-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/paganellamolveno.it\/it\/colazione-03-hotel-paganella-molveno\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/paganellamolveno.it\/wp-content\/uploads\/2019\/01\/colazione-03-hotel-paganella-molveno-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/paganellamolveno.it\/it\/colazione-01-hotel-paganella-molveno\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/paganellamolveno.it\/wp-content\/uploads\/2019\/01\/colazione-01-hotel-paganella-molveno-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row el_id=&#8221;servizi&#8221;][vc_column][vc_empty_space][vc_column_text] Servizi generali [\/vc_column_text][vc_row_inner][vc_column_inner width=&#8221;5\/12&#8243; css=&#8221;.vc_custom_1548757933648{margin-bottom: 0px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1695030465831{margin-bottom: 0px !important;}&#8221;] &#8211; ascensore &#8211; terrazza\/solarium &#8211; bar\/reception &#8211; piccolo giardino &#8211; sala TV, sala lettura &#8211; TV Sat &#8211; Trentino Card &#8211; parcheggio privato gratuito fino ad esaurimento [\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;7\/12&#8243;][vc_column_text] &#8211; WiFi gratuito &#8211; pet friendly (S\/M size) &#8211; piccolo box bici (max 6) [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":260,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"right-sidebar","site-content-layout":"plain-container","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-172","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/paganellamolveno.it\/it\/wp-json\/wp\/v2\/pages\/172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paganellamolveno.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/paganellamolveno.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/paganellamolveno.it\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/paganellamolveno.it\/it\/wp-json\/wp\/v2\/comments?post=172"}],"version-history":[{"count":54,"href":"https:\/\/paganellamolveno.it\/it\/wp-json\/wp\/v2\/pages\/172\/revisions"}],"predecessor-version":[{"id":2161,"href":"https:\/\/paganellamolveno.it\/it\/wp-json\/wp\/v2\/pages\/172\/revisions\/2161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paganellamolveno.it\/it\/wp-json\/wp\/v2\/media\/260"}],"wp:attachment":[{"href":"https:\/\/paganellamolveno.it\/it\/wp-json\/wp\/v2\/media?parent=172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}