{"id":321,"date":"2013-02-21T18:41:37","date_gmt":"2013-02-21T17:41:37","guid":{"rendered":"http:\/\/paganellamolveno.it\/?page_id=321"},"modified":"2023-02-10T10:37:19","modified_gmt":"2023-02-10T09:37:19","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/paganellamolveno.it\/it\/privacy-policy\/","title":{"rendered":"Privacy Policy"},"content":{"rendered":"<h2>Informativa sulla privacy<\/h2>\n<h3>Titolare del trattamento dei dati<\/h3>\n<p>Hotel Paganella,<br \/>\ninfo@paganellamolveno.it<\/p>\n<h3>Dati trattati e finalit\u00e0 del trattamento<\/h3>\n<p>Dati personali raccolti per le seguenti finalit\u00e0 ed utilizzando i seguenti servizi:<\/p>\n<p><i>Finalit\u00e0:<\/i> contattare l&#8217;utente.<br \/>\n<i>Dati personali raccolti:<\/i> quanto inserito nel modulo di contatto.<br \/>\n<i>Tramite:<\/i> modulo di contatto.<\/p>\n<p><i>Finalit\u00e0:<\/i> statistiche.<br \/>\n<i>Dati personali:<\/i> cookie e dati di utilizzo.<br \/>\n<i>Tramite:<\/i> Google Anaytics.<\/p>\n<h3>Ulteriori informazioni sui dati personali<\/h3>\n<p>Mai e per nessuna ragione vendiamo o affittiamo i Dati degli Utenti a terze parti. I soli usi dei Dati sono quelli evidenziati in questa policy. Gli Utenti sono gli unici proprietari dei loro Dati e possono richiederne la modifica o la cancellazione in ogni momento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informativa sulla privacy Titolare del trattamento dei dati Hotel Paganella, info@paganellamolveno.it Dati trattati e finalit\u00e0 del trattamento Dati personali raccolti per le seguenti finalit\u00e0 ed utilizzando i seguenti servizi: Finalit\u00e0: contattare l&#8217;utente. Dati personali raccolti: quanto inserito nel modulo di contatto. Tramite: modulo di contatto. Finalit\u00e0: statistiche. Dati personali: cookie e dati di utilizzo. Tramite: [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-321","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/paganellamolveno.it\/it\/wp-json\/wp\/v2\/pages\/321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paganellamolveno.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/paganellamolveno.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/paganellamolveno.it\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/paganellamolveno.it\/it\/wp-json\/wp\/v2\/comments?post=321"}],"version-history":[{"count":1,"href":"https:\/\/paganellamolveno.it\/it\/wp-json\/wp\/v2\/pages\/321\/revisions"}],"predecessor-version":[{"id":2071,"href":"https:\/\/paganellamolveno.it\/it\/wp-json\/wp\/v2\/pages\/321\/revisions\/2071"}],"wp:attachment":[{"href":"https:\/\/paganellamolveno.it\/it\/wp-json\/wp\/v2\/media?parent=321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}